{"id":470,"date":"2026-07-02T07:22:37","date_gmt":"2026-07-02T07:22:37","guid":{"rendered":"https:\/\/srtapamsmith.com\/index.php\/politica-de-cookies-ue\/"},"modified":"2026-07-02T07:22:37","modified_gmt":"2026-07-02T07:22:37","slug":"politica-de-cookies-ue","status":"publish","type":"page","link":"https:\/\/srtapamsmith.com\/index.php\/politica-de-cookies-ue\/","title":{"rendered":"Pol\u00edtica de cookies (UE)"},"content":{"rendered":"\n<!-- Legal document generated by Complianz | GDPR\/CCPA Cookie Consent https:\/\/wordpress.org\/plugins\/complianz-gdpr -->\n<div id=\"cmplz-document\" class=\"cmplz-document cookie-statement cmplz-document-eu\"><p><i>Esta pol\u00edtica de cookies fue actualizada por \u00faltima vez el julio 2, 2026 y se aplica a los ciudadanos y residentes legales permanentes del Espacio Econ\u00f3mico Europeo y Suiza.<\/i><br><\/p><h2>1. Introducci\u00f3n<\/h2><p>Nuestra web, <a href=\"https:\/\/srtapamsmith.com\">https:\/\/srtapamsmith.com<\/a> (en adelante: \u00abla web\u00bb) utiliza cookies y otras tecnolog\u00edas relacionadas (para mayor comodidad, todas las tecnolog\u00edas se denominan \u00abcookies\u00bb). Las cookies tambi\u00e9n son colocadas por terceros a los que hemos contratado. En el siguiente documento te informamos sobre el uso de cookies en nuestra web.<\/p><h2>2. \u00bfQu\u00e9 son las cookies?<\/h2><p>Una cookie es un peque\u00f1o archivo que se env\u00eda junto con las p\u00e1ginas de esta web y que tu navegador almacena en el disco duro de su ordenador u otro dispositivo. La informaci\u00f3n almacenada puede ser devuelta a nuestros servidores o a los servidores de terceros apropiados durante una visita posterior.<\/p><h2>3. \u00bfQu\u00e9 son los scripts?<\/h2><p>Un script es un fragmento de c\u00f3digo de programa que se utiliza para hacer que nuestra web funcione correctamente y de forma interactiva. Este c\u00f3digo se ejecuta en nuestro servidor o en tu dispositivo.<\/p><h2>4. \u00bfQu\u00e9 es una baliza web?<\/h2><p>Una baliza web (o una etiqueta de p\u00edxel) es una peque\u00f1a e invisible pieza de texto o imagen en una web que se utiliza para monitorear el tr\u00e1fico en una web. Para ello, se almacenan varios datos sobre usted mediante estas balizas web.<\/p><h2>5. Cookies<\/h2><h3>5.1 Cookies t\u00e9cnicas o funcionales<\/h3><p>Algunas cookies aseguran que ciertas partes de la web funcionen correctamente y que tus preferencias de usuario sigan record\u00e1ndose. Al colocar cookies funcionales, te facilitamos la visita a nuestra web. De esta manera, no necesitas introducir repetidamente la misma informaci\u00f3n cuando visitas nuestra web y, por ejemplo, los art\u00edculos permanecen en tu cesta de la compra hasta que hayas pagado. Podemos colocar estas cookies sin tu consentimiento.<\/p><h3>5.2 Cookies de marketing\/seguimiento<\/h3><p>Las cookies de marketing\/seguimiento son cookies, o cualquier otra forma de almacenamiento local, usadas para crear perfiles de usuario para mostrar publicidad o para hacer el seguimiento del usuario en esta web o en varias webs con fines de marketing similares.<\/p><h2>6. Cookies usadas<\/h2><div id=\"cmplz-cookies-overview\"><details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Varios<\/h3>\n\t\t<p>Prop\u00f3sito pendiente de investigaci\u00f3n<\/p>\n\t\t<label for=\"cmplz_service_varios\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service varios<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_varios\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"varios\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Uso<\/h4>\n\t\t<p><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartir datos<\/h4>\n\t\t<p>El intercambio de datos est\u00e1 pendiente de investigaci\u00f3n<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Prop\u00f3sito pendiente de investigaci\u00f3n<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">cmplz_functional<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">365 d\u00edas<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">cmplz_preferences<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">365 d\u00edas<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">cmplz_marketing<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">365 d\u00edas<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">cmplz_consented_services<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">365 d\u00edas<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<\/div><h2>7. Consentimiento<\/h2><p>Cuando visites nuestra web por primera vez, te mostraremos una ventana emergente con una explicaci\u00f3n sobre las cookies. Tan pronto como hagas clic en \u00abGuardar preferencias\u00bb, aceptas que usemos las categor\u00edas de cookies y plugins que has seleccionado en la ventana emergente, tal y como se describe en esta pol\u00edtica de cookies. Puedes desactivar el uso de cookies a trav\u00e9s de tu navegador, pero, por favor, ten en cuenta que nuestra web puede dejar de funcionar correctamente.<\/p><h3>7.1 Gestiona tus ajustes de consentimiento<\/h3><div id=\"cmplz-manage-consent-container-nojavascript\">Has cargado la pol\u00edtica de cookies sin compatibilidad con JavaScript.&nbsp;En AMP, puedes utilizar el bot\u00f3n de gestionar el consentimiento en la parte inferior de la p\u00e1gina.<\/div><div id=\"cmplz-manage-consent-container\" name=\"cmplz-manage-consent-container\" class=\"cmplz-manage-consent-container\"><\/div><h2>8. Activaci\u00f3n\/desactivaci\u00f3n y borrado de cookies<\/h2><p>Puedes utilizar tu navegador de Internet para eliminar las cookies de forma autom\u00e1tica o manual. Tambi\u00e9n puedes especificar que ciertas cookies no pueden ser colocadas. Otra opci\u00f3n es cambiar los ajustes de tu navegador de Internet para que recibas un mensaje cada vez que se coloca una cookie. Para obtener m\u00e1s informaci\u00f3n sobre estas opciones, consulta las instrucciones de la secci\u00f3n \u00abAyuda\u00bb de tu navegador.<\/p><p>Ten en cuenta que nuestra web puede no funcionar correctamente si todas las cookies est\u00e1n desactivadas. Si borras las cookies de tu navegador, se volver\u00e1n a colocar despu\u00e9s de tu consentimiento cuando vuelvas a visitar nuestras webs.<\/p><h2>9. Tus derechos con respecto a los datos personales<\/h2><p>Tienes los siguientes derechos con respecto a tus datos personales:<\/p><ul>\n                    <li>Tiene derecho a saber por qu\u00e9 se necesitan tus datos personales, qu\u00e9 suceder\u00e1 con ellos y durante cu\u00e1nto tiempo se conservar\u00e1n.<\/li>\n                    <li>Derecho de acceso: tienes derecho a acceder a tus datos personales que conocemos.<\/li>\n                    <li>Derecho de rectificaci\u00f3n: tienes derecho a completar, rectificar, borrar o bloquear tus datos personales cuando lo desees.<\/li>\n                    <li>Si nos das tu consentimiento para procesar tus datos, tienes derecho a revocar dicho consentimiento y a que se eliminen tus datos personales.<\/li>\n                    <li>Derecho de cesi\u00f3n de tus datos: tienes derecho a solicitar todos tus datos personales al responsable del tratamiento y a transferirlos \u00edntegramente a otro responsable del tratamiento.<\/li>\n                    <li>Derecho de oposici\u00f3n: puedes oponerte al tratamiento de tus datos. Nosotros cumplimos con esto, a menos que existan motivos justificados para el procesamiento.<\/li>\n                <\/ul><p>Para ejercer estos derechos, por favor, contacta con nosotros. Por favor, consulta los detalles de contacto en la parte inferior de esta pol\u00edtica de cookies. Si tienes alguna queja sobre c\u00f3mo gestionamos tus datos, nos gustar\u00eda que nos la hicieras saber, pero tambi\u00e9n tienes derecho a enviar una queja a la autoridad supervisora (la autoridad de protecci\u00f3n de datos).<\/p><h2>10. Datos de contacto<\/h2><p>Para preguntas y\/o comentarios sobre nuestra pol\u00edtica de cookies y esta declaraci\u00f3n, por favor, contacta con nosotros usando los siguientes datos de contacto:<\/p><p><span class=\"cmplz-contact-organisation\">Pamela Sanz Garcia<\/span><br>\n                      <span class=\"cmplz-contact-address\">Calle San Juan 31, bajo<br \/>\n15001, A Coru\u00f1a<\/span><br>\n                      <span class=\"cmplz-contact-country\">Espa\u00f1a<\/span><br>\n                      <span class=\"cmplz-contact-domain\">Web: <a href=\"https:\/\/srtapamsmith.com\">https:\/\/srtapamsmith.com<\/a><\/span><br>\n                      <span class=\"cmplz-contact-email\">Correo electr\u00f3nico: <span class=\"cmplz-obfuscate\">&#115;&#114;t&#097;&#112;a&#109;&#115;&#109;&#105;t&#104;@<span class=\"cmplz-fmail-domain\">&#101;&#120;&#046;c&#111;m<\/span>g&#109;&#097;i&#108;&#046;&#099;&#111;m<\/span><\/span><br>\n                    <span class=\"cmplz-contact-telephone\">N\u00famero de tel\u00e9fono: 611 611 438<\/span><\/p><p>Esta pol\u00edtica de cookies se ha sincronizado con <a href=\"https:\/\/cookiedatabase.org\/\" target=\"_blank\">cookiedatabase.org<\/a> el (no est\u00e1 sincronizado a\u00fan).<\/p><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-470","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/srtapamsmith.com\/index.php\/wp-json\/wp\/v2\/pages\/470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/srtapamsmith.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/srtapamsmith.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/srtapamsmith.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/srtapamsmith.com\/index.php\/wp-json\/wp\/v2\/comments?post=470"}],"version-history":[{"count":0,"href":"https:\/\/srtapamsmith.com\/index.php\/wp-json\/wp\/v2\/pages\/470\/revisions"}],"wp:attachment":[{"href":"https:\/\/srtapamsmith.com\/index.php\/wp-json\/wp\/v2\/media?parent=470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}